{"id":28304,"date":"2024-03-25T19:12:22","date_gmt":"2024-03-25T17:12:22","guid":{"rendered":"http:\/\/engind.es\/?page_id=28304"},"modified":"2025-08-22T13:52:26","modified_gmt":"2025-08-22T11:52:26","slug":"controls-inicials-i-periodics-2","status":"publish","type":"page","link":"https:\/\/engind.es\/ca\/consultoria-ingenieria\/seguimiento-de-proyectos\/controles-iniciales-y-periodicos-2\/","title":{"rendered":"Controls inicials i diaris"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFAQ\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#f7f7f7&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.24.2&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbRubik|700|||||||\u00bb header_2_font_size=\u00bb42px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb header_2_font_size_tablet=\u00bb\u00bb header_2_font_size_phone=\u00bb36px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<h2>Tipos de <span>Controles iniciales y peri\u00f3dicos<\/span><\/h2>[\/et_pb_text][et_pb_divider color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb divider_position=\u00bbcenter\u00bb divider_weight=\u00bb5px\u00bb _builder_version=\u00bb4.20.2&#8243; max_width=\u00bb50px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22color%22%93}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<h2><b>De que nos encargamos<\/b><\/h2>[\/et_pb_text][et_pb_blurb title=\u00bbInspecciones de seguridad y cumplimiento normativo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x39;||divi||400&#8243; icon_color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb56px\u00bb content_max_width=\u00bb1100px\u00bb content_max_width_tablet=\u00bb1100px\u00bb content_max_width_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.24.2&#8243; header_font=\u00bbRubik|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bb||||||||\u00bb body_text_color=\u00bb#000000&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbright\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb56px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22icon_color%22%93}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbAuditor\u00edas de calidad y medio ambiente:\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x39;||divi||400&#8243; icon_color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb56px\u00bb content_max_width=\u00bb1100px\u00bb content_max_width_tablet=\u00bb1100px\u00bb content_max_width_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.24.2&#8243; header_font=\u00bbRubik|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bb||||||||\u00bb body_text_color=\u00bb#000000&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb-21px||21px|||\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbright\u00bb animation=\u00bboff\u00bb header_font_tablet=\u00bbRubik|700|||||||\u00bb header_font_phone=\u00bbRubik|700|||||||\u00bb header_font_last_edited=\u00bbon|desktop\u00bb icon_font_size=\u00bb56px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22icon_color%22%93}\u00bb]<ul>\n<li>Auditor\u00edas de calidad ISO.<\/li>\n<li>Evaluaci\u00f3n del impacto ambiental.<\/li>\n<li>Certificaciones de gesti\u00f3n ambiental.<\/li>\n<\/ul>[\/et_pb_blurb][et_pb_blurb title=\u00bbMantenimiento preventivo y correctivo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x39;||divi||400&#8243; icon_color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb56px\u00bb content_max_width=\u00bb1100px\u00bb content_max_width_tablet=\u00bb1100px\u00bb content_max_width_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.24.2&#8243; header_font=\u00bbRubik|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bb||||||||\u00bb body_text_color=\u00bb#ffffff\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbright\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb56px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22icon_color%22%93}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbMonitoreo y control de procesos\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x39;||divi||400&#8243; icon_color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb56px\u00bb content_max_width=\u00bb1100px\u00bb content_max_width_tablet=\u00bb1100px\u00bb content_max_width_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.24.2&#8243; header_font=\u00bbRubik|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bb||||||||\u00bb body_text_color=\u00bb#ffffff\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb animation_direction=\u00bbright\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb56px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22icon_color%22%93}\u00bb][\/et_pb_blurb][et_pb_button button_url=\u00bb#contactar\u00bb button_text=\u00bbPIDE PRESUPUESTO\u00bb _builder_version=\u00bb4.20.2&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb button_border_width=\u00bb4px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb4px\u00bb button_font=\u00bbRubik|700||on|||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; custom_padding=\u00bb12px|30px|12px|30px|true|true\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_border_color_hover=\u00bb#ffb400&#8243; button_bg_color_hover=\u00bb#ffb400&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22button_text_color%22,%22button_bg_color__hover%22,%22button_border_color__hover%22%93}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bbon|desktop\u00bb button_border_color__hover=\u00bb#2e55a2&#8243; button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#2e55a2&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<p style=\"text-align: justify;\">Los <strong>controles iniciales y peri\u00f3dicos<\/strong> ofrecidos por Engind representan un pilar fundamental en la gesti\u00f3n integral de proyectos. Desde el inicio, nuestros expertos ingenieros y arquitectos se sumergen en cada detalle, asegurando que todos los aspectos del proyecto cumplan con los est\u00e1ndares de calidad y seguridad necesarios. Este enfoque proactivo nos permite identificar posibles desaf\u00edos y riesgos desde las primeras etapas, lo que a su vez facilita la implementaci\u00f3n de soluciones eficientes y efectivas.<\/p>\n<p style=\"text-align: justify;\">Durante el desarrollo del proyecto, llevamos a cabo <strong>inspecciones y controles regulares<\/strong> para garantizar que se mantenga la integridad de los procesos y que se cumplan los plazos establecidos. Nuestro equipo utiliza herramientas avanzadas y metodolog\u00edas precisas para evaluar el progreso del proyecto en tiempo real, identificando cualquier desviaci\u00f3n o discrepancia que pueda surgir.<\/p>\n<p style=\"text-align: justify;\">Uno de los aspectos clave de nuestros servicios de <strong>controles iniciales y peri\u00f3dicos<\/strong> es la atenci\u00f3n meticulosa a los detalles. Cada componente, desde la planificaci\u00f3n inicial hasta la ejecuci\u00f3n y la entrega final, se somete a una evaluaci\u00f3n exhaustiva para garantizar que cumpla con los requisitos t\u00e9cnicos y normativos. Adem\u00e1s, trabajamos en estrecha colaboraci\u00f3n con nuestros clientes para asegurarnos de que sus expectativas y necesidades sean atendidas en todo momento.<\/p>\n<p style=\"text-align: justify;\">En \u00faltima instancia, nuestro objetivo es proporcionar a las empresas la tranquilidad de saber que su proyecto est\u00e1 en buenas manos. Con Engind, no solo obtienen un equipo de expertos en ingenier\u00eda y arquitectura, sino tambi\u00e9n un socio estrat\u00e9gico comprometido con su \u00e9xito a lo largo de todo el proceso.<\/p>[\/et_pb_text][et_pb_accordion closed_toggle_text_color=\u00bb#2a2a2a\u00bb closed_toggle_background_color=\u00bb#ffffff\u00bb icon_color=\u00bbgcid-30cfe7b1-3293-4278-ab8c-450d036427bd\u00bb _builder_version=\u00bb4.21.0&#8243; toggle_font=\u00bbRubik|700|||||||\u00bb toggle_font_size=\u00bb18px\u00bb toggle_line_height=\u00bb1.4em\u00bb body_font=\u00bb||||||||\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb rank_math_faq_schema=\u00bbon\u00bb border_width_all=\u00bb0px\u00bb global_colors_info=\u00bb{%22gcid-30cfe7b1-3293-4278-ab8c-450d036427bd%22:%91%22icon_color%22%93}\u00bb][et_pb_accordion_item title=\u00bbConstrucci\u00f3n de infraestructuras\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb1px||1px||true\u00bb global_colors_info=\u00bb{}\u00bb]<p>Nos encargamos de supervisar y controlar todo tipo de construcciones. Nuestro objetivo es garantizar que los proyectos se desarrollen de acuerdo con los est\u00e1ndares de calidad, seguridad y eficiencia establecidos.<\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbDesarrollo de proyectos residenciales y comerciales\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb1px||1px||true\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<p><span>Trabajamos en estrecha colaboraci\u00f3n con promotores inmobiliarios y constructores para supervisar el desarrollo de proyectos residenciales y comerciales. <\/span><\/p>\n<p><span>Nuestro equipo se asegura de que se cumplan todos los requisitos legales y t\u00e9cnicos, y de que los proyectos se entreguen dentro de los plazos y presupuestos establecidos.<\/span><\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbEnerg\u00edas renovables\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb1px||1px||true\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<p><span>En el campo de las energ\u00edas renovables, proporcionamos servicios de project monitoring para proyectos de energ\u00eda solar, e\u00f3lica, hidroel\u00e9ctrica y biomasa. Supervisamos la construcci\u00f3n de plantas de energ\u00eda renovable, asegur\u00e1ndonos de que se cumplan los est\u00e1ndares de eficiencia y sostenibilidad.<\/span><\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbProyectos industriales\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb1px||1px||true\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<p><span>Trabajamos con empresas del sector industrial para supervisar la construcci\u00f3n de plantas de producci\u00f3n, f\u00e1bricas, <a href=\"https:\/\/engind.es\/sectores\/ingenieria-para-logistica\">centros log\u00edsticos<\/a> y otros proyectos industriales. Nuestro enfoque se centra en garantizar la eficiencia de los procesos, la seguridad laboral y el cumplimiento de las normativas ambientales.<\/span><\/p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbProyectos de infraestructuras p\u00fablicas\u00bb title_tablet=\u00bbProyectos de infraestructuras p\u00fablicas\u00bb title_phone=\u00bbProyectos de infraestructuras p\u00fablicas\u00bb title_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; custom_margin=\u00bb1px||1px||true\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<p><span>Colaboramos con entidades p\u00fablicas para supervisar la construcci\u00f3n de proyectos de infraestructuras como hospitales, escuelas, instalaciones deportivas y centros comunitarios. <\/span><\/p>\n<p><span>Nuestro objetivo es asegurar que estos proyectos cumplan con los requisitos y necesidades de la comunidad, garantizando al mismo tiempo la calidad y la sostenibilidad.<\/span><\/p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/engind.es\/wp-content\/uploads\/2024\/03\/Peticion-alta-a-companias-suministradoras.jpg\u00bb alt=\u00bbproject monitoring\u00bb title_text=\u00bbPeticio\u0301n alta a compan\u0303i\u0301as suministradoras\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/engind.es\/wp-content\/uploads\/2024\/03\/Tramitaciones-de-solicitudes-en-general.jpg\u00bb alt=\u00bbproject monitoring\u00bb title_text=\u00bbTramitaciones de solicitudes en general\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/engind.es\/wp-content\/uploads\/2024\/03\/Seguimiento-controles-iniciales.jpg\u00bb alt=\u00bbproject monitoring\u00bb title_text=\u00bbSeguimiento controles iniciales\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/engind.es\/wp-content\/uploads\/2024\/03\/Seguimiento-revisiones-periodicas-instalaciones.jpg\u00bb alt=\u00bbproject monitoring\u00bb title_text=\u00bbSeguimiento revisiones perio\u0301dicas instalaciones\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/engind.es\/wp-content\/uploads\/2024\/03\/Controles-iniciales-y-periodicos.jpg\u00bb alt=\u00bbproject monitoring\u00bb title_text=\u00bbControles iniciales y perio\u0301dicos\u00bb _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Tipos de Controles iniciales y peri\u00f3dicosDe que nos encargamos Auditor\u00edas de calidad ISO. Evaluaci\u00f3n del impacto ambiental. Certificaciones de gesti\u00f3n ambiental. Los controles iniciales y peri\u00f3dicos ofrecidos por Engind representan un pilar fundamental en la gesti\u00f3n integral de proyectos. Desde el inicio, nuestros expertos ingenieros y arquitectos se sumergen en cada detalle, asegurando que todos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28311,"parent":29799,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[],"class_list":["post-28304","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/pages\/28304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/comments?post=28304"}],"version-history":[{"count":5,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/pages\/28304\/revisions"}],"predecessor-version":[{"id":30817,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/pages\/28304\/revisions\/30817"}],"up":[{"embeddable":true,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/pages\/29799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/media\/28311"}],"wp:attachment":[{"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/media?parent=28304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engind.es\/ca\/wp-json\/wp\/v2\/categories?post=28304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}